{"id":235,"date":"2023-05-03T20:29:10","date_gmt":"2023-05-03T20:29:10","guid":{"rendered":"https:\/\/holz-und-stein-uviusfmu5c.live-website.com\/?page_id=235"},"modified":"2024-01-19T09:01:23","modified_gmt":"2024-01-19T09:01:23","slug":"kunden-ueber-uns","status":"publish","type":"page","link":"https:\/\/holz-und-stein.de\/en\/kunden-ueber-uns\/","title":{"rendered":"feedback"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"235\" class=\"elementor elementor-235\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52012d71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52012d71\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60a11eda\" data-id=\"60a11eda\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40278418 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40278418\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1142168f\" data-id=\"1142168f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fd446e elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"9fd446e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Feedbacks<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f93eb48\" data-id=\"3f93eb48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ef3c13b elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6ef3c13b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">a small selection of our customer reviews<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2bc0596 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bc0596\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9d16c16\" data-id=\"9d16c16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22bbfb1 elementor-widget elementor-widget-text-editor\" data-id=\"22bbfb1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das wertvollste in meinem Haus ist meine Sammlung an Holz &amp; Stein Stricknadeln und ich sage immer \u201ewenn\u2019s mal brennt, nehm ich auf jeden Fall diese eine Taschen mit raus\u201c. Es gibt keine Nadeln, die nur ansatzweise die gleiche Haptik haben wie Ihre. Seit der Nachricht, dass Sie in den wohlverdienten Ruhestand gegangen w\u00e4ren, habe ich gef\u00fchlt alle Qualit\u00e4ten von s\u00e4mtlichen Herstellern getestet, die ich finden konnte und immer jedem erz\u00e4hlt, dass aber nichts vergleichbar mit Ihren Nadeln ist. Und jetzt schickt mir meine Schw\u00e4gerin Ihren aktuellen Katalog zu und ich kann es fast nicht glauben! Werden die Nadeln tats\u00e4chlich weiter hergestellt? Das w\u00e4re so wunderbar!<\/p><p>Viele Gr\u00fc\u00dfe aus Hessen<\/p><p>Silke Ambos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-164914e\" data-id=\"164914e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-808b88a elementor-widget elementor-widget-text-editor\" data-id=\"808b88a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230;\u00a0\u00a0 und die Beschenkte war von den H\u00e4kelnadeln sehr begeistert. Meine Stricknadeln finde ich auch super und sie begleiten mich st\u00e4ndig bei meinen Strickprojekten. Ich stricke bisher ausschlie\u00dflich mit Holznadeln, da sie sich in der Hand gut und warm anf\u00fchlen, aber die von Holz &amp; Stein sind meiner Meinung nach auf einem anderen Level.<\/p><p>Tr\u00e2m Nguyen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f81c811\" data-id=\"f81c811\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c330e0f elementor-widget elementor-widget-text-editor\" data-id=\"c330e0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Durch die reine Holzoberfl\u00e4che rutschen die Maschen nicht eigenst\u00e4ndig, und dadurch stricke ich deutlich lockerer und entspannter, weil ich keine Bedenken mehr habe, dass die Nadel bei zu lockerem Stricken aus den Maschen gleiten k\u00f6nnte. Sch\u00f6n ist auch die Farbenvielfalt, und sehr n\u00fctzlich empfinde ich es, dass ich dunkle\/schwarze Nadeln f\u00fcr helle Wolle und helle Nadeln f\u00fcr dunkle Wolle benutzen kann. Also alles in allem ein rundum erh\u00f6hter Strickgenuss :-).<\/p><p>J. Wolf<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c1567d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1567d7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-595b335\" data-id=\"595b335\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12065cf elementor-widget elementor-widget-text-editor\" data-id=\"12065cf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich bin erleichtert, dass meine Lieblingsmanufaktur noch ein bisserl bleibt. Ich w\u00fcrd sonst das Stricken aufgeben. Denn wer einmal mit ihren Nadeln gestrickt hat, r\u00fchrt keine anderen mehr an!<\/p><p>Ihre Rundstricknadeln sind auch die feinsten, die ich kenne, was den \u00dcbergang zwischen Holz und Faden betrifft. Und die Feinheit der Spitze ist eh ungeschlagen!<\/p><p>Jutta Stadler<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c985e21\" data-id=\"c985e21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a05acc elementor-widget elementor-widget-text-editor\" data-id=\"4a05acc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ihre Nadeln sind m.E. die hochwertigsten, die auf dem Markt erh\u00e4ltlich sind &#8211; kein Vergleich zu anderen Edelholz-Nadeln, die ich nat\u00fcrlich auch ausprobiert, jedoch schnell wieder verworfen habe. Ich nehme immer wieder am liebsten Ihre Nadeln in die Hand.<\/p><p>T. Rausch<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-28e430f\" data-id=\"28e430f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0496113 elementor-widget elementor-widget-text-editor\" data-id=\"0496113\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; die Stricknadel ist wieder heil bei mir angekommen. Ich m\u00f6chte mich vielmals bei Ihnen f\u00fcr Ihre M\u00fche bedanken. So einen reibunglosen Ablauf wie bei Ihnen habe ich in letzter Zeit sehr selten erlebt.<\/p><p>&#8230; und Ihre Auswahl im Katalog ist unglaublich toll.<\/p><p>Sabine Ba.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8982e98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8982e98\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e94833c\" data-id=\"e94833c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1251d0f elementor-widget elementor-widget-text-editor\" data-id=\"1251d0f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Thank you very much, Ursula. I am excited to have some new and beautiful needles. You all do such lovely work. The circular needles with their sturdy \u201cinternal\u201d join are just the best in the whole wide world.<\/p><p>Until next time,\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lisa Frank \/ USA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-90a46dd\" data-id=\"90a46dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fb8faa elementor-widget elementor-widget-text-editor\" data-id=\"5fb8faa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ach, eine Frage habe ich noch &#8211; obgleich es ja schon so oft als Ger\u00fccht verbreitet wurde: Sie h\u00f6ren nicht auf, oder? Das w\u00e4re sehr schade, denn ich liebe ihre Nadeln sehr (und den Service und das Konzept und \u00fcberhaupt alles) und bin schon seit bestimmt einem Jahrzehnt begeisterte Holz&amp;Stein-Strickerin.<\/p><p>Katja Emb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a3d5f77\" data-id=\"a3d5f77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1634459 elementor-widget elementor-widget-text-editor\" data-id=\"1634459\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Nadelspiele sind gestern wohl-behalten eingetroffen und wurden gleich getestet. Meine Begeisterung kann ich kaum in Worte fassen &#8211; vor allem die Nadeln aus Bloodwood sind der Hammer und drum bestell ich auch gleich nochmal \ud83d\ude09<\/p><p>Anita Th.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55ce451 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55ce451\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-67816dc\" data-id=\"67816dc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a1e0f1 elementor-widget elementor-widget-text-editor\" data-id=\"9a1e0f1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I receive needles today. Your needles are very perfect.<br \/>I think that your needles are the best in the earth.<\/p>\n<p>I will buy more needles in the near future.<\/p>\n<p>Really thanks. Bye \ud83d\ude42<br \/>KIM YU MI \u2013 South Korea<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ff24391\" data-id=\"ff24391\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d03eccc elementor-widget elementor-widget-text-editor\" data-id=\"d03eccc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Ware ist angekommen, und wie immer WUNDERBAR!<\/p><p>Die H\u00e4kelnadeln mit Griff sind ja der Oberhammer. Hatte nicht gewusst, dass Sie auch solche machen. Sie liegen wunderbar in der Hand und f\u00fchlen sich ganz toll an.<\/p><p>Sie und Ihr Team haben wieder ganze Arbeit geleistet.<\/p><p>M. Schmidt<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-688510a\" data-id=\"688510a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e58cb2b elementor-widget elementor-widget-text-editor\" data-id=\"e58cb2b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230;\u00a0 vielen, vielen Dank f\u00fcr die herrlichen Nadeln.\u00a0 Die sind ein absoluter Traum, besonders die Amarello gefallen mir sehr sehr gut, und es strickt sich wie von selbst. Absolute Handschmeichler.<\/p><p>Vicky I.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-aaf918a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aaf918a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eccb71c\" data-id=\"eccb71c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d7f4e1 elementor-widget elementor-widget-text-editor\" data-id=\"8d7f4e1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ihre Nadeln sind ja der Porsche unter den Stricknadeln und mit weitem Abstand die Allerbesten. Ich nehme keine anderen mehr und w\u00fcrde lieber mit dem Stricken aufh\u00f6ren, als den Hersteller zu wechseln!<\/p><p>Jutta Stadler<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bc522cb\" data-id=\"bc522cb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a91c453 elementor-widget elementor-widget-text-editor\" data-id=\"a91c453\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I ordered needles some time ago and wanted to let you know that they are awesome. Thank you for such a great product.<\/p><p>Gabriele Eleby \/ USA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-40f9c09\" data-id=\"40f9c09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7dd8afe elementor-widget elementor-widget-text-editor\" data-id=\"7dd8afe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich bin so froh, dass ich Sie gefunden habe. Es strickt sich super mit den sch\u00f6nen Nadeln und jeder, der mich sieht, bleibt erst einmal stehen. So was haben sie noch nie gesehen. Daher habe ich auch schon mehrfach ihre Adresse weitergegeben und hoffe , dass Sie schon ein paar Auftr\u00e4ge erhalten haben.<\/p><p>Sabine Vi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ac3e45d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac3e45d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c08d509\" data-id=\"c08d509\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a6b2d8 elementor-widget elementor-widget-text-editor\" data-id=\"2a6b2d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; besten Dank f\u00fcr die Zusendung der Stricknadeln, Eine sch\u00f6ner als die Andere, will sagen, alle traumhaft sch\u00f6n, ein wahrer Augenschmaus (und erst f\u00fcr die H\u00e4nde!) Und die Kn\u00f6pfe sind auch wunder-, wundersch\u00f6n.<br \/>Ich flitze gleich r\u00fcber auf&#8217;s Sofa zum Stricken :-))))<\/p><p>Pia Rosen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2380b93\" data-id=\"2380b93\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cc7363 elementor-widget elementor-widget-text-editor\" data-id=\"3cc7363\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; Und was soll ich sagen, ein Traum des Strickens.<br \/>Diese Nadeln sind einfach wundervoll.<br \/>F\u00fcr mich sind die Nadeln von Ihnen ein Geschenk.<br \/>Daf\u00fcr bedanke ich mich auf diesem Weg noch einmal!<\/p><p>C. Nartmann<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f45c235\" data-id=\"f45c235\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ebe269 elementor-widget elementor-widget-text-editor\" data-id=\"8ebe269\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; received my needles and the beautiful wood pen.<\/p><p>Thank you very much for the best needles ever made! The finest workmanship\u00a0I have ever seen.<\/p><p>Best Regards, Barbara Perlik \/ USA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c8628c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8628c4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-23f977f\" data-id=\"23f977f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75fe151 elementor-widget elementor-widget-text-editor\" data-id=\"75fe151\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; und bin schlicht begeistert. Das Ebenholz f\u00fchlt sich wunderbar in der Hand an. Sehr viel angenehmer (irgendwie weicher, elastischer, w\u00e4rmer) als meine bisherigen Holz-Nadelspitzen. Die Rutschigkeit des Ebenholzes ist mit der verwendeten Wolle ideal. Nicht zuuuu rutschig, aber glatt genug, dass die Maschen gut \u00fcber die Nadel laufen. Der \u00dcbergang zum Seil ist auch fantastisch.<\/p><p>Antje Kam.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f6f902\" data-id=\"7f6f902\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95e5cbf elementor-widget elementor-widget-text-editor\" data-id=\"95e5cbf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Nadeln sind wie immer ein Traum!\u00a0 Ich habe nun schon eine sch\u00f6ne Sammlung, vor allem an Rundstricknadeln, aber man kann einfach nicht genug haben. Ich liebe dieses nat\u00fcrliche Holz (Rosenholz). Sie sind viel sch\u00f6ner und besser als diese bunten aus den USA (die dann auch noch wer-wei\u00df- wo gefertigt werden). Mit dem \u00dcbergang zum Seil k\u00f6nnen die sowieso nicht mithalten.<\/p><p>Nina Le.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-de89dfb\" data-id=\"de89dfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e3f137 elementor-widget elementor-widget-text-editor\" data-id=\"4e3f137\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich habe 2 Sets von den Strumpfstrick-nadeln aus Elfenbeinholz gekauft. Ein Set habe ich meiner Mutter geschenkt und ein Set war f\u00fcr mich.<br \/>Seitdem schw\u00e4rmen wir jedes mal, wenn wir uns \u00fcber das Stricken unterhalten, von euren Nadeln. Es gibt wirklich keinen Vergleich dazu.<br \/>Wir dachten uns, da\u00df mu\u00df mal gesagt werden.<\/p><p>M. Gehringer<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f2bbb41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2bbb41\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b41d762\" data-id=\"b41d762\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ce70f5 elementor-widget elementor-widget-text-editor\" data-id=\"0ce70f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I received the needles and wanted to tell you how beautiful they are and how wonderful they are to knit with. Holz &amp; Stein are my cousin&#8217;s favorite needles so I bought some for myself. What a delightful surprise! I especially like the tip of the needle.<\/p><p>Trina Bortko \/ USA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e54f939\" data-id=\"e54f939\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3998be8 elementor-widget elementor-widget-text-editor\" data-id=\"3998be8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich bin mit Ihrer Firma und den Nadeln sehr zufrieden!<br \/>Ich stricke seit Jahren nur mehr ausschlie\u00dflich damit und kann mir was anderes nicht mehr vorstellen!<\/p><p>mit lieben Gr\u00fc\u00dfen aus Wien<br \/>Elisabeth Peleska<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-092f4fa\" data-id=\"092f4fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e94bfc elementor-widget elementor-widget-text-editor\" data-id=\"8e94bfc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230;\u00a0 die Nadeln sind heute angekommen, und ich finde sie wundersch\u00f6n! Bin mal gespannt auf&#8217;s Stricken. Meine Schwester hat sich in M\u00fcnchen auch sofort welche gekauft und berichtete, das sei &#8222;eine Offenbarung&#8220;.<\/p><p>Gr\u00fc\u00dfe von M. Reims<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c678f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c678f2\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-dad6fe6\" data-id=\"dad6fe6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-616a2b7 elementor-widget elementor-widget-text-editor\" data-id=\"616a2b7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Nadeln sind angekommen und ich kann nur sagen: Ich bin begeistert und beeindruckt vom handwerklichen K\u00f6nnen Ihrer Mitarbeiter.<br \/>Das Material f\u00fchlt sich wunderbar an, schmeichelt den H\u00e4nden, und wie ich nach ersten Versuchen beurteile, gleitet die Wolle wunderbar auf dem edlen Holz. Auch gef\u00e4llt mir die Farbe des Ebenholzes und der Seidenglanz, der vermutlich durch die fachkundige Bearbeitung und Behandlung des Holzes entsteht, ganz besonders!<br \/>Ich wiederhole es gerne noch einmal: einfach grossartig, und ich freue mich auf nachher, wenn ich wieder stricken kann!<br \/>M.B. Kip. \/ Schweiz<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b9ddee5\" data-id=\"b9ddee5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14a2d81 elementor-widget elementor-widget-text-editor\" data-id=\"14a2d81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>..\u00a0 ich hatte ja versprochen, mich nochmals zu melden, wenn ich die Nadeln auch ausprobiert habe.<br \/>Ich bin sooo begeistert! Ich habe jetzt sowohl die Veilchenholznadeln als auch die Rosenholznadeln ausprobiert und finde beide absolut hervorragend! Ein Strickerlebnis ohne Vergleich&#8230; Ich habe vorher mit Bambus und Harmony Wood gestrickt&#8230; Die waren schon viel angenehmer als Metallnadeln. Aber diese Nadeln hier sind wirklich mit NICHTS anderem zu vergleichen und eigentlich unbeschreiblich \ud83d\ude42<br \/>Nicht nur, dass sie enorm leicht sind, sondern auch sehr angenehm warm und griffig. Ich habe nicht das Gef\u00fchl dauernd aufpassen zu m\u00fcssen, dass mir Maschen von der Nadel gleiten&#8230; Ein wirklich sehr entspanntes Stricken !<\/p><p>Claudia Hab.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f866ac\" data-id=\"7f866ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6167ecc elementor-widget elementor-widget-text-editor\" data-id=\"6167ecc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230;\u00a0 erhalten und war, wie immer, begeistert von der Sch\u00f6nheit und Qualit\u00e4t der Nadeln. Besonders die Nadeln aus Veilchenholz gefallen mir sehr gut und sehen noch besser aus als auf Ihren Fotos. Ich freue mich schon aufs Sockenstricken und habe sofort die Bambusnadeln in die Reservekiste verbannt.<\/p><p>Herzlichen Dank m\u00f6chte ich sagen f\u00fcr den sehr kulanten Ersatz meiner zerbrochenen Rundstricknadel. Das erlebe ich heute kaum noch.<\/p><p>Christiane \u00d6.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4079df9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4079df9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eb567b2\" data-id=\"eb567b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02525fe elementor-widget elementor-widget-text-editor\" data-id=\"02525fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; Nun zu den Nadeln. Ich wei\u00df nicht, mit welch guten W\u00fcnschen und mit welchem Segen Sie Ihre Stricknadeln aus der Manufaktur &#8222;entlassen&#8220;, aber ich bin mir sicher, dass jede einzelne der Nadeln stolz darauf ist, stricken zu d\u00fcrfen. Es w\u00e4re jetzt gelogen zu sagen, sie tun die Arbeit von alleine. Aber es ist die Wahrheit, wenn ich Ihnen versichere, dass die Freude an der Handarbeit mit Ihren tollen Nadeln noch gr\u00f6\u00dfer wird! Weiter so, bitte.<\/p><p>Petra Gatterer<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6a1f1ba\" data-id=\"6a1f1ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ec05d4 elementor-widget elementor-widget-text-editor\" data-id=\"6ec05d4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seit ich eure Holznadelspiele besitze, nutze ich nichts anderes mehr! Die sanfte Oberfl\u00e4che und die wunderbaren Farben der H\u00f6lzer sprechen mich genauso an, wie die unbestreitbaren Vorteile beim Stricken: durch das geringe Gewicht rutschen mir die Nadeln nicht mehr aus den Maschen, und vor allem quillt das Holz bei feuchten H\u00e4nden nicht auf, wie ich das bei Bambusnadeln immer hatte, wodurch die Wolle dann so gar nicht mehr \u00fcber die Nadeln rutschen wollte.<br \/>Eure edlen Holznadeln haben mich auf ganzer Linie erobert und ich empfehle sie flei\u00dfig anderen vielstrickenden Bekannten und Freunden.<\/p>\n<p>Anna Wessel<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ea56bc8\" data-id=\"ea56bc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d166a2 elementor-widget elementor-widget-text-editor\" data-id=\"1d166a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Begriff Stricknadeln ist weit untertrieben, ich w\u00fcrde es eher mein bestes virtuoses Lieblingshandwerkszeug nennen! Ich arbeitete noch niemals mit etwas Besserem als den Veilchenholznadeln und w\u00fcrde am liebsten ein lustiges Lagerfeuer mit meinen anderen Nadeln veranstalten oder sie nur noch zum Mikado spielen oder Schaschlik stecken benutzen. Tja, Sie sind schuld, da\u00df meine Nadelkollektion nun eine Statistenrolle beim Verwahren der angefangenen Strickprojekte hat :-).<\/p><p>Cl. H\u00f6ll<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-dbb57dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dbb57dd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-438b672\" data-id=\"438b672\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-863b236 elementor-widget elementor-widget-text-editor\" data-id=\"863b236\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ich habe die Stricknadeln gestern erhalten und nat\u00fcrlich gleich ausprobiert. Ich bin begeistert. Ich habe das Gef\u00fchl, man h\u00e4lt die Stricknadeln automatisch anders, nicht mehr so fest, man k\u00f6nnte meinen, nicht mehr so verkrampft und &#8211; meine rheumatischen H\u00e4nde freuen sich.<\/p><p>Kristin Mah.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a8b678a\" data-id=\"a8b678a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c9b642 elementor-widget elementor-widget-text-editor\" data-id=\"5c9b642\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Stricknadeln sind bereits am Montag wohlbehalten bei mir eingetroffen und seitdem im Dauereinsatz. Mit ihnen strickt sich einfach federleicht, und man hat das Gef\u00fchl, die Maschen rutschen auf einem Luftkissen. Dazu kommt die gute Stabilit\u00e4t: man hat nicht dieses &#8222;aufgeweichte&#8220; Gef\u00fchl, das sich bei Bambusnadeln nach l\u00e4ngerem Gebrauch zeigt. Ich m\u00f6chte nicht mehr auf Ihre Nadeln verzichten<\/p><p>J\u00fcrgen Fi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1b8fc4b\" data-id=\"1b8fc4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e141c7d elementor-widget elementor-widget-text-editor\" data-id=\"e141c7d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; die \u00fcberarbeitete Stricknadel ist inzwischen wieder bei mir angekommen und funktioniert wieder tadellos. Das Stricken mit Ihren Nadeln ist echt ein Genu\u00df, und wenn man diese Holznadeln einmal gew\u00f6hnt ist, m\u00f6chte man mit nichts anderem mehr arbeiten.<\/p><p>E. Lang<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19dd7a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19dd7a7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4b091d4\" data-id=\"4b091d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fc7544 elementor-widget elementor-widget-text-editor\" data-id=\"3fc7544\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nicht dass sie meinen, ich \u00fcbertreibe. Ich habe mir vor kurzem Rundstricknadeln gekauft (20cm), weil ich nicht wusste, dass Sie diese auch herstellen &#8211; und wirklich, ich konnte sie nicht benutzen, weil ich mit der stumpfen Spitze nicht zurecht kam. Selbst die KnitPro, welche ich mir im gro\u00dfen Set kaufte, als ich noch nicht wusste, dass es Holz &amp; Stein gibt, bereiten mir keine Freude mehr. Mit Ihren Nadeln ist das Stricken wirklich Entspannung pur! Ganz herzlichen Dank an Sie und Ihr Team!!!<\/p><p>Katja Eh.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8b9a213\" data-id=\"8b9a213\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16b3663 elementor-widget elementor-widget-text-editor\" data-id=\"16b3663\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8230; das Paket mit den Stricknadeln ist wohlbehalten angekommen &#8211; und ich freue mich, mit diesen wunderbaren Nadeln zu arbeiten. Jede Masche flutscht, es ist herrlich!<\/p><p>A. Eckert<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1b82453\" data-id=\"1b82453\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-732aa2f e-flex e-con-boxed e-con e-parent\" data-id=\"732aa2f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f7ebd35 elementor-widget elementor-widget-template\" data-id=\"f7ebd35\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"7069\" class=\"elementor elementor-7069\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73f5291b e-con-full e-flex e-con e-parent\" data-id=\"73f5291b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e0de40f e-con-full e-flex e-con e-parent\" data-id=\"4e0de40f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1f185668 e-con-full e-flex e-con e-parent\" data-id=\"1f185668\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-378d908 elementor-nav-menu__align-center elementor-nav-menu--dropdown-none elementor-widget-tablet__width-auto elementor-widget__width-auto elementor-widget-mobile__width-auto elementor-widget elementor-widget-nav-menu\" data-id=\"378d908\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<div id=\"menu-1-378d908\" class=\"elementor-nav-menu\"><li class=\"page_item page-item-7686\"><a href=\"https:\/\/holz-und-stein.de\/en\/bestaetigung-anfrage-katalog\/\">Best\u00e4tigung Anfrage Katalog<\/a><\/li>\n<li class=\"page_item page-item-7463\"><a href=\"https:\/\/holz-und-stein.de\/en\/cookie-richtlinie-eu\/\">cookie policy<\/a><\/li>\n<li class=\"page_item page-item-5832\"><a href=\"https:\/\/holz-und-stein.de\/en\/datenschutzerklaerung\/\">privacy policy *<\/a><\/li>\n<li class=\"page_item page-item-7501\"><a href=\"https:\/\/holz-und-stein.de\/en\/download-cataloge\/\">Download Cataloge<\/a><\/li>\n<li class=\"page_item page-item-4470\"><a href=\"https:\/\/holz-und-stein.de\/en\/farbchema\/\">Farbchema<\/a><\/li>\n<li class=\"page_item page-item-242\"><a href=\"https:\/\/holz-und-stein.de\/en\/haekelnadeln\/\">crochet hooks<\/a><\/li>\n<li class=\"page_item page-item-4600\"><a href=\"https:\/\/holz-und-stein.de\/en\/\">Home<\/a><\/li>\n<li class=\"page_item page-item-1927\"><a href=\"https:\/\/holz-und-stein.de\/en\/impressum\/\">legal notice<\/a><\/li>\n<li class=\"page_item page-item-7490\"><a href=\"https:\/\/holz-und-stein.de\/en\/katalog-auswahl\/\">Katalog Auswahl<\/a><\/li>\n<li class=\"page_item page-item-7321\"><a href=\"https:\/\/holz-und-stein.de\/en\/katalog-anfrage\/\">Katalog-Anfrage<\/a><\/li>\n<li class=\"page_item page-item-4783\"><a href=\"https:\/\/holz-und-stein.de\/en\/knoepfe\/\">buttons<\/a><\/li>\n<li class=\"page_item page-item-274\"><a href=\"https:\/\/holz-und-stein.de\/en\/kontakt\/\">contact<\/a><\/li>\n<li class=\"page_item page-item-235\"><a href=\"https:\/\/holz-und-stein.de\/en\/kunden-ueber-uns\/\">feedback<\/a><\/li>\n<li class=\"page_item page-item-5671\"><a href=\"https:\/\/holz-und-stein.de\/en\/manufaktur\/\">Manufactory<\/a><\/li>\n<li class=\"page_item page-item-7432\"><a href=\"https:\/\/holz-und-stein.de\/en\/newsletter\/\">newsletter<\/a><\/li>\n<li class=\"page_item page-item-7440\"><a href=\"https:\/\/holz-und-stein.de\/en\/newsletter-abbonieren\/\">Subscribe to Newsletter<\/a><\/li>\n<li class=\"page_item page-item-7740\"><a href=\"https:\/\/holz-und-stein.de\/en\/newsletter-bestaetigung\/\">Newsletter Best\u00e4tigung<\/a><\/li>\n<li class=\"page_item page-item-94\"><a href=\"https:\/\/holz-und-stein.de\/en\/nuetzlinge\/\">tools<\/a><\/li>\n<li class=\"page_item page-item-7718\"><a href=\"https:\/\/holz-und-stein.de\/en\/optin-newsletter\/\">Opt-In Newsletter<\/a><\/li>\n<li class=\"page_item page-item-236\"><a href=\"https:\/\/holz-und-stein.de\/en\/produkte\/\">products<\/a><\/li>\n<li class=\"page_item page-item-114\"><a href=\"https:\/\/holz-und-stein.de\/en\/stricknadeln\/\">knitting needles<\/a><\/li>\n<li class=\"page_item page-item-3302\"><a href=\"https:\/\/holz-und-stein.de\/en\/tuchbroschen\/\">scarf brooches<\/a><\/li>\n<li class=\"page_item page-item-90\"><a href=\"https:\/\/holz-und-stein.de\/en\/tuchnadeln\/\">scarf needles<\/a><\/li>\n<li class=\"page_item page-item-231\"><a href=\"https:\/\/holz-und-stein.de\/en\/unsere-hoelzer\/\">wood types<\/a><\/li>\n<li class=\"page_item page-item-96\"><a href=\"https:\/\/holz-und-stein.de\/en\/wir-ueber-uns\/\">about us<\/a><\/li>\n<\/div>\n\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<div id=\"menu-2-378d908\" class=\"elementor-nav-menu\"><li class=\"page_item page-item-7686\"><a href=\"https:\/\/holz-und-stein.de\/en\/bestaetigung-anfrage-katalog\/\">Best\u00e4tigung Anfrage Katalog<\/a><\/li>\n<li class=\"page_item page-item-7463\"><a href=\"https:\/\/holz-und-stein.de\/en\/cookie-richtlinie-eu\/\">cookie policy<\/a><\/li>\n<li class=\"page_item page-item-5832\"><a href=\"https:\/\/holz-und-stein.de\/en\/datenschutzerklaerung\/\">privacy policy *<\/a><\/li>\n<li class=\"page_item page-item-7501\"><a href=\"https:\/\/holz-und-stein.de\/en\/download-cataloge\/\">Download Cataloge<\/a><\/li>\n<li class=\"page_item page-item-4470\"><a href=\"https:\/\/holz-und-stein.de\/en\/farbchema\/\">Farbchema<\/a><\/li>\n<li class=\"page_item page-item-242\"><a href=\"https:\/\/holz-und-stein.de\/en\/haekelnadeln\/\">crochet hooks<\/a><\/li>\n<li class=\"page_item page-item-4600\"><a href=\"https:\/\/holz-und-stein.de\/en\/\">Home<\/a><\/li>\n<li class=\"page_item page-item-1927\"><a href=\"https:\/\/holz-und-stein.de\/en\/impressum\/\">legal notice<\/a><\/li>\n<li class=\"page_item page-item-7490\"><a href=\"https:\/\/holz-und-stein.de\/en\/katalog-auswahl\/\">Katalog Auswahl<\/a><\/li>\n<li class=\"page_item page-item-7321\"><a href=\"https:\/\/holz-und-stein.de\/en\/katalog-anfrage\/\">Katalog-Anfrage<\/a><\/li>\n<li class=\"page_item page-item-4783\"><a href=\"https:\/\/holz-und-stein.de\/en\/knoepfe\/\">buttons<\/a><\/li>\n<li class=\"page_item page-item-274\"><a href=\"https:\/\/holz-und-stein.de\/en\/kontakt\/\">contact<\/a><\/li>\n<li class=\"page_item page-item-235\"><a href=\"https:\/\/holz-und-stein.de\/en\/kunden-ueber-uns\/\">feedback<\/a><\/li>\n<li class=\"page_item page-item-5671\"><a href=\"https:\/\/holz-und-stein.de\/en\/manufaktur\/\">Manufactory<\/a><\/li>\n<li class=\"page_item page-item-7432\"><a href=\"https:\/\/holz-und-stein.de\/en\/newsletter\/\">newsletter<\/a><\/li>\n<li class=\"page_item page-item-7440\"><a href=\"https:\/\/holz-und-stein.de\/en\/newsletter-abbonieren\/\">Subscribe to Newsletter<\/a><\/li>\n<li class=\"page_item page-item-7740\"><a href=\"https:\/\/holz-und-stein.de\/en\/newsletter-bestaetigung\/\">Newsletter Best\u00e4tigung<\/a><\/li>\n<li class=\"page_item page-item-94\"><a href=\"https:\/\/holz-und-stein.de\/en\/nuetzlinge\/\">tools<\/a><\/li>\n<li class=\"page_item page-item-7718\"><a href=\"https:\/\/holz-und-stein.de\/en\/optin-newsletter\/\">Opt-In Newsletter<\/a><\/li>\n<li class=\"page_item page-item-236\"><a href=\"https:\/\/holz-und-stein.de\/en\/produkte\/\">products<\/a><\/li>\n<li class=\"page_item page-item-114\"><a href=\"https:\/\/holz-und-stein.de\/en\/stricknadeln\/\">knitting needles<\/a><\/li>\n<li class=\"page_item page-item-3302\"><a href=\"https:\/\/holz-und-stein.de\/en\/tuchbroschen\/\">scarf brooches<\/a><\/li>\n<li class=\"page_item page-item-90\"><a href=\"https:\/\/holz-und-stein.de\/en\/tuchnadeln\/\">scarf needles<\/a><\/li>\n<li class=\"page_item page-item-231\"><a href=\"https:\/\/holz-und-stein.de\/en\/unsere-hoelzer\/\">wood types<\/a><\/li>\n<li class=\"page_item page-item-96\"><a href=\"https:\/\/holz-und-stein.de\/en\/wir-ueber-uns\/\">about us<\/a><\/li>\n<\/div>\n\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-831926d e-flex e-con-boxed e-con e-parent\" data-id=\"831926d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d77e76 elementor-widget elementor-widget-template\" data-id=\"1d77e76\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"7072\" class=\"elementor elementor-7072\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76fd4497 e-con-full e-flex e-con e-parent\" data-id=\"76fd4497\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-57828bc7 e-con-full e-flex e-con e-parent\" data-id=\"57828bc7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-75a08e37 e-con-full e-flex e-con e-parent\" data-id=\"75a08e37\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-132b1da0 elementor-widget__width-auto elementor-widget-tablet__width-auto elementor-widget elementor-widget-heading\" data-id=\"132b1da0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">\u00a9 2026 - All rights reserved. Designed by Holz &amp; Stein.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Feedbacks Eine kleine Auswahl unserer Kundenzuschriften. Das wertvollste in meinem Haus ist meine Sammlung an Holz &amp; Stein Stricknadeln und ich sage immer \u201ewenn\u2019s mal brennt, nehm ich auf jeden Fall diese eine Taschen mit raus\u201c. Es gibt keine Nadeln, die nur ansatzweise die gleiche Haptik haben wie Ihre. Seit der Nachricht, dass Sie in [&hellip;]<\/p>","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"off","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-235","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/pages\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":0,"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/pages\/235\/revisions"}],"wp:attachment":[{"href":"https:\/\/holz-und-stein.de\/en\/wp-json\/wp\/v2\/media?parent=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}